{"id":21,"count":3,"description":"","link":"http:\/\/www.emmebiitalia.com.hk\/hair-care\/category\/stories\/","name":"Stories","slug":"stories","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"http:\/\/www.emmebiitalia.com.hk\/hair-care\/wp-json\/wp\/v2\/categories\/21","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.emmebiitalia.com.hk\/hair-care\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"http:\/\/www.emmebiitalia.com.hk\/hair-care\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"http:\/\/www.emmebiitalia.com.hk\/hair-care\/wp-json\/wp\/v2\/posts?categories=21"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}